{"id":2763,"date":"2023-12-27T14:30:51","date_gmt":"2023-12-27T21:30:51","guid":{"rendered":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/"},"modified":"2023-12-27T14:30:51","modified_gmt":"2023-12-27T21:30:51","slug":"wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one","status":"publish","type":"post","link":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/","title":{"rendered":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one"},"content":{"rendered":"<div><img decoding=\"async\" src=\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&#038;tl=1\"><\/p>\n<div>Starting Wednesday, the fast-food chain is offering Jr. Bacon Cheeseburgers for just one penny at participating locations.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Starting Wednesday, the fast-food chain is offering Jr. Bacon Cheeseburgers for just one penny at&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona\" \/>\n<meta property=\"og:description\" content=\"Starting Wednesday, the fast-food chain is offering Jr. Bacon Cheeseburgers for just one penny at...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\" \/>\n<meta property=\"og:site_name\" content=\"CBS26 Arizona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CBSNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-27T21:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1\" \/>\n<meta name=\"author\" content=\"cbs26.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CBSNews\" \/>\n<meta name=\"twitter:site\" content=\"@CBSNews\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cbs26.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\"},\"author\":{\"name\":\"cbs26.com\",\"@id\":\"https:\/\/cbs26.com\/#\/schema\/person\/6f199387dd167b788a14f8b99f8ff352\"},\"headline\":\"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one\",\"datePublished\":\"2023-12-27T21:30:51+00:00\",\"dateModified\":\"2023-12-27T21:30:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\"},\"wordCount\":33,\"publisher\":{\"@id\":\"https:\/\/cbs26.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\",\"url\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\",\"name\":\"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona\",\"isPartOf\":{\"@id\":\"https:\/\/cbs26.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1\",\"datePublished\":\"2023-12-27T21:30:51+00:00\",\"dateModified\":\"2023-12-27T21:30:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage\",\"url\":\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1\",\"contentUrl\":\"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cbs26.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cbs26.com\/#website\",\"url\":\"https:\/\/cbs26.com\/\",\"name\":\"CBS26 Arizona\",\"description\":\"The Spirit of Arizona\",\"publisher\":{\"@id\":\"https:\/\/cbs26.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cbs26.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cbs26.com\/#organization\",\"name\":\"CBS26 Arizona\",\"url\":\"https:\/\/cbs26.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cbs26.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cbs26.com\/wp-content\/uploads\/2023\/12\/cbs26.fw_-1-e1703104627272.png\",\"contentUrl\":\"https:\/\/cbs26.com\/wp-content\/uploads\/2023\/12\/cbs26.fw_-1-e1703104627272.png\",\"width\":296,\"height\":96,\"caption\":\"CBS26 Arizona\"},\"image\":{\"@id\":\"https:\/\/cbs26.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CBSNews\/\",\"https:\/\/x.com\/CBSNews\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cbs26.com\/#\/schema\/person\/6f199387dd167b788a14f8b99f8ff352\",\"name\":\"cbs26.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cbs26.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5c693e6a74bdbc1461a75db724fe465?s=96&d=mm&r=r\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5c693e6a74bdbc1461a75db724fe465?s=96&d=mm&r=r\",\"caption\":\"cbs26.com\"},\"sameAs\":[\"http:\/\/cbs26.com\"],\"url\":\"https:\/\/cbs26.com\/index.php\/author\/cbs26-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/","og_locale":"en_GB","og_type":"article","og_title":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona","og_description":"Starting Wednesday, the fast-food chain is offering Jr. Bacon Cheeseburgers for just one penny at...","og_url":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/","og_site_name":"CBS26 Arizona","article_publisher":"https:\/\/www.facebook.com\/CBSNews\/","article_published_time":"2023-12-27T21:30:51+00:00","og_image":[{"url":"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1"}],"author":"cbs26.com","twitter_card":"summary_large_image","twitter_creator":"@CBSNews","twitter_site":"@CBSNews","twitter_misc":{"Written by":"cbs26.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#article","isPartOf":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/"},"author":{"name":"cbs26.com","@id":"https:\/\/cbs26.com\/#\/schema\/person\/6f199387dd167b788a14f8b99f8ff352"},"headline":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one","datePublished":"2023-12-27T21:30:51+00:00","dateModified":"2023-12-27T21:30:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/"},"wordCount":33,"publisher":{"@id":"https:\/\/cbs26.com\/#organization"},"image":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage"},"thumbnailUrl":"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1","articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/","url":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/","name":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one - CBS26 Arizona","isPartOf":{"@id":"https:\/\/cbs26.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage"},"image":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage"},"thumbnailUrl":"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1","datePublished":"2023-12-27T21:30:51+00:00","dateModified":"2023-12-27T21:30:51+00:00","breadcrumb":{"@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#primaryimage","url":"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1","contentUrl":"https:\/\/images.CBS26tv.com\/static.CBS26phoenix.com\/www.CBS26phoenix.com\/content\/uploads\/2023\/12\/1280\/720\/cheeseburger-wendys-getty.jpg?ve=1&tl=1"},{"@type":"BreadcrumbList","@id":"https:\/\/cbs26.com\/index.php\/2023\/12\/27\/wendys-jr-bacon-cheeseburgers-are-only-1-cent-this-week-heres-how-to-get-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbs26.com\/"},{"@type":"ListItem","position":2,"name":"Wendy\u2019s Jr. Bacon Cheeseburgers are only 1 cent this week \u2013 here\u2019s how to get one"}]},{"@type":"WebSite","@id":"https:\/\/cbs26.com\/#website","url":"https:\/\/cbs26.com\/","name":"CBS26 Arizona","description":"The Spirit of Arizona","publisher":{"@id":"https:\/\/cbs26.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbs26.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cbs26.com\/#organization","name":"CBS26 Arizona","url":"https:\/\/cbs26.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cbs26.com\/#\/schema\/logo\/image\/","url":"https:\/\/cbs26.com\/wp-content\/uploads\/2023\/12\/cbs26.fw_-1-e1703104627272.png","contentUrl":"https:\/\/cbs26.com\/wp-content\/uploads\/2023\/12\/cbs26.fw_-1-e1703104627272.png","width":296,"height":96,"caption":"CBS26 Arizona"},"image":{"@id":"https:\/\/cbs26.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CBSNews\/","https:\/\/x.com\/CBSNews"]},{"@type":"Person","@id":"https:\/\/cbs26.com\/#\/schema\/person\/6f199387dd167b788a14f8b99f8ff352","name":"cbs26.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cbs26.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5c693e6a74bdbc1461a75db724fe465?s=96&d=mm&r=r","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5c693e6a74bdbc1461a75db724fe465?s=96&d=mm&r=r","caption":"cbs26.com"},"sameAs":["http:\/\/cbs26.com"],"url":"https:\/\/cbs26.com\/index.php\/author\/cbs26-com\/"}]}},"_links":{"self":[{"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/posts\/2763"}],"collection":[{"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/comments?post=2763"}],"version-history":[{"count":0,"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/posts\/2763\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/media?parent=2763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/categories?post=2763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbs26.com\/index.php\/wp-json\/wp\/v2\/tags?post=2763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}